{"id":1938,"date":"2025-05-30T14:19:28","date_gmt":"2025-05-30T14:19:28","guid":{"rendered":"https:\/\/mznoticia.com.br\/jaguariaiva\/?p=1938"},"modified":"2025-05-30T14:19:28","modified_gmt":"2025-05-30T14:19:28","slug":"parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/","title":{"rendered":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira"},"content":{"rendered":"<p>As temperaturas continuaram caindo no Paran\u00e1 nesta sexta-feira (20) e a primeira temperatura negativa de 2025 foi registrada no Estado. A esta\u00e7\u00e3o meteorol\u00f3gica do Sistema de Tecnologia e Monitoramento Ambiental do Paran\u00e1 (Simepar) que fica no distrito de Horizonte, em Palmas, na regi\u00e3o Sul do Estado, detectou a temperatura de -0,3\u00b0C \u00e0s 8h30.<\/p>\n<p>Outras 26 esta\u00e7\u00f5es, em 25 cidades, registraram nesta sexta-feira novamente a menor temperatura do ano at\u00e9 o momento. As temperaturas mais baixas do Estado, al\u00e9m dos -0,3\u00b0C de Horizonte, em Palmas, foram no Centro de Palmas (1.5\u00b0C \u00e0s 7h), Santa Maria do Oeste (2\u00b0C \u00e0s 7h), Palotina (1.8\u00b0C \u00e0s 7h), Pinhais (2.6\u00b0C \u00e0s 6h), Ponta Grossa (1.7\u00b0C \u00e0s 7h), e Toledo (0.8\u00b0C \u00e0s 5h).<\/p>\n<p>A sensa\u00e7\u00e3o t\u00e9rmica, um c\u00e1lculo feito levando em conta a temperatura e o vento para considerar como \u00e9 a percep\u00e7\u00e3o f\u00edsica das pessoas com rela\u00e7\u00e3o a temperatura registrada, foi negativa em algumas esta\u00e7\u00f5es: Cascavel: -1,7\u00b0C; Centro de Palmas: -1,4\u00b0C; Distrito de Horizonte, em Palmas: -4\u00b0C; Ponta Grossa: -1,1\u00b0C; e Toledo: -1,8\u00b0C.<\/p>\n<p><strong>Esta\u00e7\u00f5es com c\u00e1lculo de menor sensa\u00e7\u00e3o t\u00e9rmica no Paran\u00e1 nesta sexta-feira:<\/strong><\/p>\n<p>Assis Chateaubriand: 1,4\u00b0C<\/p>\n<p>Cambar\u00e1: 1,3\u00b0C<\/p>\n<p>Campo Mour\u00e3o: 1,2\u00b0C<\/p>\n<p>Cascavel: -1,7\u00b0C<\/p>\n<p>Curitiba: 1,9\u00b0C<\/p>\n<p>Distrito de Entre Rios (Guarapuava) e Fazenda Rio Grande: 0,1\u00b0C<\/p>\n<p>Fernandes Pinheiro: 1,6\u00b0C<\/p>\n<p>Jaguaria\u00edva: 0,9\u00b0C<\/p>\n<p>Lapa: 1,1\u00b0C<\/p>\n<p>Laranjeiras do Sul: 0,6\u00b0C<\/p>\n<p>Palmas: -1,4\u00b0C<\/p>\n<p>Palmas &#8211; Horizonte: -4\u00b0C<\/p>\n<p>Palmital &#8211; Santa Maria: 0,1\u00b0C<\/p>\n<p>Palotina: 0\u00b0C<\/p>\n<p>Pinhais: 1\u00b0C<\/p>\n<p>Ponta Grossa: -1,1\u00b0C<\/p>\n<p>Tel\u00eamaco Boba: 1,6\u00b0C<\/p>\n<p>Toledo: -1,8\u00b0C<\/p>\n<p>Ubirat\u00e3: 1\u00b0C<\/p>\n<p><strong>Lista das 26 esta\u00e7\u00f5es do Simepar que atingiram novamente a menor temperatura do ano nesta sexta-feira:<\/strong><\/p>\n<p>Antonina: 9.3\u00b0C \u00e0s 07h<\/p>\n<p>Assis Chateaubriand: 3.8\u00b0C \u00e0s 3h<\/p>\n<p>Cambar\u00e1: 2.3\u00b0C \u00e0s 5h<\/p>\n<p>Campo Mour\u00e3o: 3.4\u00b0C \u00e0s 6h<\/p>\n<p>Cascavel: 2.4\u00b0C \u00e0s 6h<\/p>\n<p>Cerro Azul: 4.5\u00b0C \u00e0s 7h<\/p>\n<p>Curitiba: 4.1\u00b0C \u00e0s 5h<\/p>\n<p>Fazenda Rio Grande: 2.4\u00b0C \u00e0s 4h<\/p>\n<p>Guaira: 3.5\u00b0C \u00e0s 7h<\/p>\n<p>Guaratuba: 11\u00b0C \u00e0s 7h<\/p>\n<p>Jaguariaiva: 3.6\u00b0C \u00e0s 7h<\/p>\n<p>Lapa: 3.6\u00b0C \u00e0 0h<\/p>\n<p>Palmas: 1.5\u00b0C \u00e0s 7h<\/p>\n<p>Palmas &#8211; Horizonte: 0\u00b0C \u00e0s 7h<\/p>\n<p>Palmital &#8211; Santa Maria: 2\u00b0C \u00e0s 7h<\/p>\n<p>Palotina: 1.8\u00b0C \u00e0s 7h<\/p>\n<p>Paranagu\u00e1: 11.4\u00b0C \u00e0s 7h<\/p>\n<p>Paranava\u00ed: 5.2\u00b0C \u00e0s 4h<\/p>\n<p>Pinhais: 2.6\u00b0C \u00e0s 6h<\/p>\n<p>Ponta Grossa: 1.7\u00b0C \u00e0s 7h<\/p>\n<p>Guaraque\u00e7aba: 7.2\u00b0C \u00e0s 6h<\/p>\n<p>Santa Helena: 5\u00b0C \u00e0s 4h<\/p>\n<p>Tel\u00eamaco Borba: 3.5\u00b0C \u00e0s 7h<\/p>\n<p>Toledo: 0.8\u00b0C \u00e0s 5h<\/p>\n<p>Umuarama: 3.1\u00b0C \u00e0s 7h<\/p>\n<p>Uni\u00e3o da Vit\u00f3ria: 5.6\u00b0C \u00e0s 6h<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As temperaturas continuaram caindo no Paran\u00e1 nesta sexta-feira (20) e a primeira temperatura negativa de 2025 foi registrada no Estado. A esta\u00e7\u00e3o meteorol\u00f3gica do Sistema de Tecnologia e Monitoramento Ambiental do Paran\u00e1 (Simepar) que fica no distrito de Horizonte, em Palmas, na regi\u00e3o Sul do Estado, detectou a temperatura de -0,3\u00b0C \u00e0s 8h30. Outras 26 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[47],"class_list":["post-1938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campos-gerais","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"As temperaturas continuaram caindo no Paran\u00e1 nesta sexta-feira (20) e a primeira temperatura negativa de 2025 foi registrada no Estado. A esta\u00e7\u00e3o meteorol\u00f3gica do Sistema de Tecnologia e Monitoramento Ambiental do Paran\u00e1 (Simepar) que fica no distrito de Horizonte, em Palmas, na regi\u00e3o Sul do Estado, detectou a temperatura de -0,3\u00b0C \u00e0s 8h30. Outras 26 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T14:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1060\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira\",\"datePublished\":\"2025-05-30T14:19:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Campos Gerais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/\",\"name\":\"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg\",\"datePublished\":\"2025-05-30T14:19:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg\",\"width\":1060,\"height\":596},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/","og_locale":"pt_BR","og_type":"article","og_title":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias","og_description":"As temperaturas continuaram caindo no Paran\u00e1 nesta sexta-feira (20) e a primeira temperatura negativa de 2025 foi registrada no Estado. A esta\u00e7\u00e3o meteorol\u00f3gica do Sistema de Tecnologia e Monitoramento Ambiental do Paran\u00e1 (Simepar) que fica no distrito de Horizonte, em Palmas, na regi\u00e3o Sul do Estado, detectou a temperatura de -0,3\u00b0C \u00e0s 8h30. Outras 26 [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-05-30T14:19:28+00:00","og_image":[{"width":1060,"height":596,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira","datePublished":"2025-05-30T14:19:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg","keywords":["destaque"],"articleSection":["Campos Gerais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/","name":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg","datePublished":"2025-05-30T14:19:28+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/05\/Inverno-e-a-terceira-idade-entenda-por-que-o-idoso-sente-muito-frio-1060x596-11.jpg","width":1060,"height":596},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/parana-registra-primeira-temperatura-negativa-de-2025-nesta-sexta-feira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"Paran\u00e1 registra primeira temperatura negativa de 2025 nesta sexta-feira"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":1,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/1938\/revisions"}],"predecessor-version":[{"id":1940,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/1938\/revisions\/1940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/1939"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=1938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=1938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}