{"id":2654,"date":"2025-09-22T17:01:24","date_gmt":"2025-09-22T17:01:24","guid":{"rendered":"https:\/\/mznoticia.com.br\/piraidosul\/?p=2654"},"modified":"2025-09-22T17:01:45","modified_gmt":"2025-09-22T17:01:45","slug":"procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/","title":{"rendered":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel"},"content":{"rendered":"<p>O celular tornou-se uma ferramenta quase indispens\u00e1vel para a popula\u00e7\u00e3o e, para compreender como os consumidores avaliam os servi\u00e7os oferecidos, o Procon-PR (Coordena\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o e Defesa do Consumidor), vinculado \u00e0 Secretaria de Estado da Justi\u00e7a e Cidadania (Seju), promoveu uma pesquisa online nos dias 18 e 19 de setembro. Ao todo, 2,1 mil pessoas responderam e ajudaram a identificar a percep\u00e7\u00e3o dos usu\u00e1rios sobre os planos de telefonia m\u00f3vel.<\/p>\n<p>Os resultados mostram que 51,5% dos consumidores consideram que as informa\u00e7\u00f5es sobre o funcionamento do seu plano de telefonia n\u00e3o s\u00e3o acess\u00edveis e claras. Al\u00e9m disso, 76,8% dos usu\u00e1rios informaram j\u00e1 ter tido problemas com sua operadora de celular.\u00a0A pesquisa revela que apenas 16,8% dos usu\u00e1rios est\u00e3o totalmente satisfeitos com a operadora contratada, enquanto 63,8% declaram estar apenas parcialmente satisfeitas e 19,4% afirmam estar insatisfeitos.<\/p>\n<p>\u201cOs dados demonstram que as empresas precisam adotar medidas que assegurem maior transpar\u00eancia e qualidade nas informa\u00e7\u00f5es repassadas aos clientes\u201d, diz Valdemar Jorge, secret\u00e1rio da Justi\u00e7a e Cidadania.<\/p>\n<p>Segundo o Procon-PR, dos quase 100 mil atendimentos registrados em 2025 na plataforma\u00a0<strong><a class=\"0\" href=\"https:\/\/consumidor.gov.br\/pages\/principal\/?1758550106637\" target=\"_blank\" rel=\"nofollow noopener\">consumidor.gov.br<\/a><\/strong>, cerca de 15 mil est\u00e3o relacionados a problemas com operadoras de telecomunica\u00e7\u00f5es, incluindo telefonia, televis\u00e3o por assinatura e internet.<\/p>\n<p>Entre as principais queixas dos consumidores est\u00e3o cobran\u00e7as indevidas, tarifas por servi\u00e7os n\u00e3o solicitados, cobran\u00e7as ap\u00f3s o cancelamento do contrato, ofertas n\u00e3o cumpridas, entre outras.<\/p>\n<p>A coordenadora do Procon-PR, Claudia Silvano, faz um alerta sobre os dados da pesquisa e refor\u00e7a a import\u00e2ncia da entrada em vigor do Regulamento Geral de Direitos do Consumidor de Servi\u00e7os de Telecomunica\u00e7\u00f5es (Resolu\u00e7\u00e3o n\u00ba 765\/2023).<\/p>\n<p>\u201cO consumidor deve ficar atento e sempre conferir sua conta, fatura ou a utiliza\u00e7\u00e3o no aplicativo. Caso identifique alguma diverg\u00eancia ou problema, pode registrar a reclama\u00e7\u00e3o na plataforma\u00a0<strong><a class=\"0\" href=\"https:\/\/consumidor.gov.br\/pages\/principal\/?1758550106637\" target=\"_blank\" rel=\"nofollow noopener\">consumidor.gov.br<\/a><\/strong>, que possui prazo de resposta de at\u00e9 10 dias e \u00edndice de resolu\u00e7\u00e3o pr\u00f3ximo a 80%\u201d, orienta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O celular tornou-se uma ferramenta quase indispens\u00e1vel para a popula\u00e7\u00e3o e, para compreender como os consumidores avaliam os servi\u00e7os oferecidos, o Procon-PR (Coordena\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o e Defesa do Consumidor), vinculado \u00e0 Secretaria de Estado da Justi\u00e7a e Cidadania (Seju), promoveu uma pesquisa online nos dias 18 e 19 de setembro. Ao todo, 2,1 mil [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[47],"class_list":["post-2654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campos-gerais","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O celular tornou-se uma ferramenta quase indispens\u00e1vel para a popula\u00e7\u00e3o e, para compreender como os consumidores avaliam os servi\u00e7os oferecidos, o Procon-PR (Coordena\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o e Defesa do Consumidor), vinculado \u00e0 Secretaria de Estado da Justi\u00e7a e Cidadania (Seju), promoveu uma pesquisa online nos dias 18 e 19 de setembro. Ao todo, 2,1 mil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T17:01:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T17:01:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1878\" \/>\n\t<meta property=\"og:image:height\" content=\"1252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel\",\"datePublished\":\"2025-09-22T17:01:24+00:00\",\"dateModified\":\"2025-09-22T17:01:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20211220_agb_procon_pr-2.jpg\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Campos Gerais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/\",\"name\":\"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20211220_agb_procon_pr-2.jpg\",\"datePublished\":\"2025-09-22T17:01:24+00:00\",\"dateModified\":\"2025-09-22T17:01:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20211220_agb_procon_pr-2.jpg\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20211220_agb_procon_pr-2.jpg\",\"width\":1878,\"height\":1252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/","og_locale":"pt_BR","og_type":"article","og_title":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias","og_description":"O celular tornou-se uma ferramenta quase indispens\u00e1vel para a popula\u00e7\u00e3o e, para compreender como os consumidores avaliam os servi\u00e7os oferecidos, o Procon-PR (Coordena\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o e Defesa do Consumidor), vinculado \u00e0 Secretaria de Estado da Justi\u00e7a e Cidadania (Seju), promoveu uma pesquisa online nos dias 18 e 19 de setembro. Ao todo, 2,1 mil [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-09-22T17:01:24+00:00","article_modified_time":"2025-09-22T17:01:45+00:00","og_image":[{"width":1878,"height":1252,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel","datePublished":"2025-09-22T17:01:24+00:00","dateModified":"2025-09-22T17:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg","keywords":["destaque"],"articleSection":["Campos Gerais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/","name":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg","datePublished":"2025-09-22T17:01:24+00:00","dateModified":"2025-09-22T17:01:45+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/20211220_agb_procon_pr-2.jpg","width":1878,"height":1252},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/procon-pr-pesquisa-a-percepcao-dos-consumidores-sobre-planos-de-telefonia-movel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"Procon-PR pesquisa a percep\u00e7\u00e3o dos consumidores sobre planos de telefonia m\u00f3vel"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=2654"}],"version-history":[{"count":1,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2654\/revisions"}],"predecessor-version":[{"id":2657,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2654\/revisions\/2657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/2655"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=2654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=2654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=2654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}