{"id":2671,"date":"2025-09-23T17:30:08","date_gmt":"2025-09-23T17:30:08","guid":{"rendered":"https:\/\/mznoticia.com.br\/piraidosul\/?p=2671"},"modified":"2025-09-23T17:30:08","modified_gmt":"2025-09-23T17:30:08","slug":"pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/","title":{"rendered":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o"},"content":{"rendered":"<p>A Pol\u00edcia Civil do Paran\u00e1 (PCPR) prendeu sete pessoas durante uma opera\u00e7\u00e3o policial contra suspeitos de tr\u00e1fico de drogas, lavagem de dinheiro, organiza\u00e7\u00e3o criminosa e porte ilegal de armas. A investiga\u00e7\u00e3o indica que o grupo movimentou cerca de R$ 2,5 milh\u00f5es em um m\u00eas. A a\u00e7\u00e3o aconteceu na manh\u00e3 desta ter\u00e7a-feira (23) em Curitiba, Piraquara e Pinhais, na Regi\u00e3o Metropolitana de Curitiba; Jacarezinho, no Norte Pioneiro; Laranjeiras do Sul, na regi\u00e3o Centro-Sul; Saudade do Igua\u00e7u, no Sudoeste; e Pira\u00ed do Sul, nos Campos Gerais.<\/p>\n<p>Ao todo, foram executados 24 mandados de busca e apreens\u00e3o, sete de pris\u00e3o preventiva e oito de quebra de sigilo de dados de tornozeleiras eletr\u00f4nicas. A opera\u00e7\u00e3o contou com o apoio da Pol\u00edcia Militar do Paran\u00e1 (PMPR) e com a atua\u00e7\u00e3o de c\u00e3es de faro das duas institui\u00e7\u00f5es, que refor\u00e7aram a efic\u00e1cia das buscas.<\/p>\n<p>Nos endere\u00e7os, os policiais apreenderam duas armas de fogo, uma arma longa, muni\u00e7\u00f5es calibre 9mm (de uso restrito) e .38, al\u00e9m de um colete bal\u00edstico e muni\u00e7\u00f5es deflagradas.<\/p>\n<p>Esta \u00e9 a quarta fase da opera\u00e7\u00e3o. \u201cEsta fase \u00e9 resultado de um aprofundamento das investiga\u00e7\u00f5es, iniciadas em maio de 2024, por meio das quais conseguimos identificar pessoas que continuavam atuando no tr\u00e1fico, especificamente na distribui\u00e7\u00e3o de drogas\u201d, afirma o delegado da PCPR Thiago Andrade.<\/p>\n<p>A fase anterior foi deflagrada em maio deste ano e resultou na pris\u00e3o de seis pessoas investigadas por tr\u00e1fico de drogas. Na ocasi\u00e3o, a PCPR apreendeu celulares que posteriormente passaram por per\u00edcia.<\/p>\n<p>As informa\u00e7\u00f5es extra\u00eddas dos aparelhos mostraram que o grupo atuava com a negocia\u00e7\u00e3o de toneladas de drogas por meio de aplicativos de mensagem e com o gerenciamento de toda a log\u00edstica para o seu envio a Curitiba, Norte do Paran\u00e1 e S\u00e3o Paulo. Paralelamente a esta atividade, os investigados negociavam armamentos e ostentavam o seu uso em redes sociais.<\/p>\n<p>O esquema funcionava com base em uma cadeia de informantes e compradores e mantinha rela\u00e7\u00f5es com uma organiza\u00e7\u00e3o criminosa de atua\u00e7\u00e3o nacional. Os investigados tamb\u00e9m dispunham de um galp\u00e3o para fazer o armazenamento da droga e ve\u00edculos pr\u00f3prios para fazer a sua distribui\u00e7\u00e3o.<\/p>\n<p>A an\u00e1lise do material extra\u00eddo dos aparelhos mostrou ainda que as movimenta\u00e7\u00f5es financeiras e transa\u00e7\u00f5es via Pix dos investigados s\u00e3o compat\u00edveis com a lavagem de capitais para ocultar a origem il\u00edcita dos valores.<\/p>\n<p>Os presos foram encaminhados ao sistema penitenci\u00e1rio. A PCPR seguir\u00e1 com as investiga\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil do Paran\u00e1 (PCPR) prendeu sete pessoas durante uma opera\u00e7\u00e3o policial contra suspeitos de tr\u00e1fico de drogas, lavagem de dinheiro, organiza\u00e7\u00e3o criminosa e porte ilegal de armas. A investiga\u00e7\u00e3o indica que o grupo movimentou cerca de R$ 2,5 milh\u00f5es em um m\u00eas. A a\u00e7\u00e3o aconteceu na manh\u00e3 desta ter\u00e7a-feira (23) em Curitiba, Piraquara [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[47],"class_list":["post-2671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Civil do Paran\u00e1 (PCPR) prendeu sete pessoas durante uma opera\u00e7\u00e3o policial contra suspeitos de tr\u00e1fico de drogas, lavagem de dinheiro, organiza\u00e7\u00e3o criminosa e porte ilegal de armas. A investiga\u00e7\u00e3o indica que o grupo movimentou cerca de R$ 2,5 milh\u00f5es em um m\u00eas. A a\u00e7\u00e3o aconteceu na manh\u00e3 desta ter\u00e7a-feira (23) em Curitiba, Piraquara [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T17:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o\",\"datePublished\":\"2025-09-23T17:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/vanderlim_0.jpg\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Policial\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/\",\"name\":\"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/vanderlim_0.jpg\",\"datePublished\":\"2025-09-23T17:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/vanderlim_0.jpg\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/vanderlim_0.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/","og_locale":"pt_BR","og_type":"article","og_title":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias","og_description":"A Pol\u00edcia Civil do Paran\u00e1 (PCPR) prendeu sete pessoas durante uma opera\u00e7\u00e3o policial contra suspeitos de tr\u00e1fico de drogas, lavagem de dinheiro, organiza\u00e7\u00e3o criminosa e porte ilegal de armas. A investiga\u00e7\u00e3o indica que o grupo movimentou cerca de R$ 2,5 milh\u00f5es em um m\u00eas. A a\u00e7\u00e3o aconteceu na manh\u00e3 desta ter\u00e7a-feira (23) em Curitiba, Piraquara [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-09-23T17:30:08+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o","datePublished":"2025-09-23T17:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg","keywords":["destaque"],"articleSection":["Policial"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/","name":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg","datePublished":"2025-09-23T17:30:08+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/09\/vanderlim_0.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pcpr-identifica-movimentacao-de-r-25-milhoes-do-trafico-e-prende-sete-pessoas-em-operacao-pirai-do-sul-foi-alvo-da-acao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"PCPR identifica movimenta\u00e7\u00e3o de R$ 2,5 milh\u00f5es do tr\u00e1fico e prende sete pessoas em opera\u00e7\u00e3o; Pira\u00ed do Sul foi alvo da a\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=2671"}],"version-history":[{"count":1,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2671\/revisions"}],"predecessor-version":[{"id":2674,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2671\/revisions\/2674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/2672"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=2671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}