{"id":2796,"date":"2025-10-02T14:00:23","date_gmt":"2025-10-02T14:00:23","guid":{"rendered":"https:\/\/mznoticia.com.br\/piraidosul\/?p=2796"},"modified":"2025-10-02T14:00:23","modified_gmt":"2025-10-02T14:00:23","slug":"saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/","title":{"rendered":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest"},"content":{"rendered":"<p data-start=\"325\" data-end=\"832\">A Prefeitura de Pira\u00ed do Sul vai gastar em torno de R$ 1,2 milh\u00e3o apenas com a contrata\u00e7\u00e3o de artistas nacionais que ir\u00e3o se apresentar na 4\u00aa Pira\u00ed Rodeo Fest, programada para os dias 10 a 12 de outubro no Antigo Campo de Avia\u00e7\u00e3o, no Bairro das Brotas. Os dados constam em documentos oficiais do Processo Administrativo n\u00ba 878\/2025, da Secretaria Municipal de Esportes e Turismo, que tratou das contrata\u00e7\u00f5es por inexigibilidade de licita\u00e7\u00e3o, amparadas pelo artigo 74 da Lei n\u00ba 14.133\/2021.<\/p>\n<p data-start=\"834\" data-end=\"876\">Os valores confirmados s\u00e3o os seguintes:<\/p>\n<ul data-start=\"878\" data-end=\"1247\">\n<li data-start=\"878\" data-end=\"995\">\n<p data-start=\"880\" data-end=\"995\">Leonardo: R$\u00a0 690 mil, contratado pela empresa Talism\u00e3 Administradora de Shows e Editora Musical Ltda.<\/p>\n<\/li>\n<li data-start=\"996\" data-end=\"1091\">\n<p data-start=\"998\" data-end=\"1091\">Humberto &amp; Ronaldo: R$ 296.100, contratados pela MAA Produ\u00e7\u00f5es Art\u00edsticas Ltda.<\/p>\n<\/li>\n<li data-start=\"1092\" data-end=\"1190\">\n<p data-start=\"1094\" data-end=\"1190\">Gian &amp; Giovani: R$ 215 mil, contratados pela Marcinho Costa Eventos Musicais Ltda.<\/p>\n<\/li>\n<li data-start=\"1191\" data-end=\"1247\">\n<p data-start=\"1193\" data-end=\"1247\">J\u00fanior Villa: valor n\u00e3o apurado at\u00e9 o momento, mas o cach\u00ea varia e costuma ser mais de R$ 25 mil.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1249\" data-end=\"1381\">Somados, os contratos j\u00e1 conhecidos ultrapassam R$ 1,2 milh\u00e3o em recursos destinados exclusivamente \u00e0s apresenta\u00e7\u00f5es musicais.<\/p>\n<h3 data-start=\"1383\" data-end=\"1408\">Estrutura do evento<\/h3>\n<p data-start=\"1410\" data-end=\"1666\">Al\u00e9m dos cach\u00eas dos artistas, a empresa Drial Organiza\u00e7\u00e3o de Eventos Esportivos Ltda. venceu a licita\u00e7\u00e3o para explora\u00e7\u00e3o do espa\u00e7o p\u00fablico da festa, que inclui estrutura, pra\u00e7a de alimenta\u00e7\u00e3o, equipamentos e m\u00e3o de obra, pelo valor de R$ 157 mil. Com isso, o custo total \u00e9 de R$ 1.358.100.<\/p>\n<h3 data-start=\"1668\" data-end=\"1693\">Programa\u00e7\u00e3o musical<\/h3>\n<ul data-start=\"1695\" data-end=\"1848\">\n<li data-start=\"1695\" data-end=\"1748\">\n<p data-start=\"1697\" data-end=\"1748\">Sexta-feira (10\/10): Humberto &amp; Ronaldo \u2013 23h<\/p>\n<\/li>\n<li data-start=\"1749\" data-end=\"1808\">\n<p data-start=\"1751\" data-end=\"1808\">S\u00e1bado (11\/10): Gian &amp; Giovani e J\u00fanior Villa \u2013 23h<\/p>\n<\/li>\n<li data-start=\"1809\" data-end=\"1848\">\n<p data-start=\"1811\" data-end=\"1848\">Domingo (12\/10): Leonardo \u2013 22h<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1850\" data-end=\"1873\">Tradi\u00e7\u00e3o e rodeio<\/h3>\n<p data-start=\"1875\" data-end=\"2106\">A festa tamb\u00e9m contar\u00e1 com as tradicionais montarias em touros do Circuito de Rodeio \u2013 Duelo de Gigantes, que garantir\u00e1 ao campe\u00e3o local uma vaga na final da Liga Nacional de Rodeio em Barretos, o maior da Am\u00e9rica Latina.<\/p>\n<h3 data-start=\"2108\" data-end=\"2131\">Escolha da Rainha<\/h3>\n<p data-start=\"2133\" data-end=\"2374\">A abertura simb\u00f3lica da programa\u00e7\u00e3o ser\u00e1 neste s\u00e1bado (4 de outubro), com a escolha da Rainha do Rodeio, al\u00e9m da 1\u00aa e 2\u00aa Princesas e da Madrinha dos Pe\u00f5es, no Gin\u00e1sio Samuel Mill\u00e9o, a partir das 19h30. A entrada \u00e9 gratuita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Pira\u00ed do Sul vai gastar em torno de R$ 1,2 milh\u00e3o apenas com a contrata\u00e7\u00e3o de artistas nacionais que ir\u00e3o se apresentar na 4\u00aa Pira\u00ed Rodeo Fest, programada para os dias 10 a 12 de outubro no Antigo Campo de Avia\u00e7\u00e3o, no Bairro das Brotas. Os dados constam em documentos oficiais do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[47],"class_list":["post-2796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-piraidosul","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Pira\u00ed do Sul vai gastar em torno de R$ 1,2 milh\u00e3o apenas com a contrata\u00e7\u00e3o de artistas nacionais que ir\u00e3o se apresentar na 4\u00aa Pira\u00ed Rodeo Fest, programada para os dias 10 a 12 de outubro no Antigo Campo de Avia\u00e7\u00e3o, no Bairro das Brotas. Os dados constam em documentos oficiais do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T14:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest\",\"datePublished\":\"2025-10-02T14:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Pira\u00ed do Sul\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/\",\"name\":\"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp\",\"datePublished\":\"2025-10-02T14:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/","og_locale":"pt_BR","og_type":"article","og_title":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias","og_description":"A Prefeitura de Pira\u00ed do Sul vai gastar em torno de R$ 1,2 milh\u00e3o apenas com a contrata\u00e7\u00e3o de artistas nacionais que ir\u00e3o se apresentar na 4\u00aa Pira\u00ed Rodeo Fest, programada para os dias 10 a 12 de outubro no Antigo Campo de Avia\u00e7\u00e3o, no Bairro das Brotas. Os dados constam em documentos oficiais do [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-10-02T14:00:23+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest","datePublished":"2025-10-02T14:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp","keywords":["destaque"],"articleSection":["Pira\u00ed do Sul"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/","name":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp","datePublished":"2025-10-02T14:00:23+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/Confira-a-agenda-de-shows-do-cantor-sertanejo-Leonardo.webp1_.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/saiba-o-valor-gasto-com-os-tres-shows-nacionais-para-a-4a-pirai-rodeo-fest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"Saiba o valor gasto com os tr\u00eas shows nacionais para a 4\u00aa Pira\u00ed Rodeo Fest"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=2796"}],"version-history":[{"count":1,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2796\/revisions"}],"predecessor-version":[{"id":2798,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2796\/revisions\/2798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/2797"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=2796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=2796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=2796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}