{"id":2821,"date":"2025-10-03T13:35:31","date_gmt":"2025-10-03T13:35:31","guid":{"rendered":"https:\/\/mznoticia.com.br\/piraidosul\/?p=2821"},"modified":"2025-10-03T13:37:05","modified_gmt":"2025-10-03T13:37:05","slug":"pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/","title":{"rendered":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:30a1e8c5-715c-4860-badb-225119667a28-4\" data-testid=\"conversation-turn-10\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"d59699d4-11d4-4041-8d99-a220b539aef3\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"67\" data-end=\"236\">A Pol\u00edcia Rodovi\u00e1ria Estadual (PRE) informou que um acidente sem v\u00edtimas foi registrado no final da manh\u00e3 desta quinta-feira (2), no km 163 da PR-090, em Pira\u00ed do Sul.<\/p>\n<p data-start=\"238\" data-end=\"536\">Conforme o relat\u00f3rio, o conjunto de ve\u00edculos de carga, formado por um caminh\u00e3o Volvo FH, emplacado em Tarum\u00e3 (SP), e dois semirreboques Librelato, seguia no sentido Ventania a Pira\u00ed do Sul quando um dos pneus estourou antes de uma curva. Com isso, o segundo semirreboque tombou sobre a pista, na regi\u00e3o da Serrinha.<\/p>\n<p data-start=\"538\" data-end=\"705\" data-is-last-node=\"\" data-is-only-node=\"\">O motorista, de 27 anos, n\u00e3o se feriu. O tr\u00e2nsito ficou parcialmente interditado e passou a fluir em sistema pare-e-siga pela via marginal at\u00e9 a libera\u00e7\u00e3o do trecho. A carga de gr\u00e3os espalhou pela pista, o que necessitou de limpeza para libera\u00e7\u00e3o com seguran\u00e7a.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\">Vale lembrar que o local j\u00e1 registrou outros acidentes recentes nos \u00faltimos meses. a curva \u00e9 bastante fechada em trecho de descida- sentido qual o caminh\u00e3o seguia.<\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Estadual (PRE) informou que um acidente sem v\u00edtimas foi registrado no final da manh\u00e3 desta quinta-feira (2), no km 163 da PR-090, em Pira\u00ed do Sul. Conforme o relat\u00f3rio, o conjunto de ve\u00edculos de carga, formado por um caminh\u00e3o Volvo FH, emplacado em Tarum\u00e3 (SP), e dois semirreboques Librelato, seguia no sentido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[47],"class_list":["post-2821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Rodovi\u00e1ria Estadual (PRE) informou que um acidente sem v\u00edtimas foi registrado no final da manh\u00e3 desta quinta-feira (2), no km 163 da PR-090, em Pira\u00ed do Sul. Conforme o relat\u00f3rio, o conjunto de ve\u00edculos de carga, formado por um caminh\u00e3o Volvo FH, emplacado em Tarum\u00e3 (SP), e dois semirreboques Librelato, seguia no sentido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-03T13:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T13:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul\",\"datePublished\":\"2025-10-03T13:35:31+00:00\",\"dateModified\":\"2025-10-03T13:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/\"},\"wordCount\":174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Policial\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/\",\"name\":\"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg\",\"datePublished\":\"2025-10-03T13:35:31+00:00\",\"dateModified\":\"2025-10-03T13:37:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg\",\"width\":960,\"height\":760},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/","og_locale":"pt_BR","og_type":"article","og_title":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias","og_description":"A Pol\u00edcia Rodovi\u00e1ria Estadual (PRE) informou que um acidente sem v\u00edtimas foi registrado no final da manh\u00e3 desta quinta-feira (2), no km 163 da PR-090, em Pira\u00ed do Sul. Conforme o relat\u00f3rio, o conjunto de ve\u00edculos de carga, formado por um caminh\u00e3o Volvo FH, emplacado em Tarum\u00e3 (SP), e dois semirreboques Librelato, seguia no sentido [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-10-03T13:35:31+00:00","article_modified_time":"2025-10-03T13:37:05+00:00","og_image":[{"width":960,"height":760,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul","datePublished":"2025-10-03T13:35:31+00:00","dateModified":"2025-10-03T13:37:05+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/"},"wordCount":174,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg","keywords":["destaque"],"articleSection":["Policial"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/","name":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg","datePublished":"2025-10-03T13:35:31+00:00","dateModified":"2025-10-03T13:37:05+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-02-at-18.12.31.jpeg","width":960,"height":760},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/pre-detalha-tombamento-de-carreta-na-pr-090-em-pirai-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"PRE detalha tombamento de carreta na PR-090 em Pira\u00ed do Sul"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=2821"}],"version-history":[{"count":3,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2821\/revisions"}],"predecessor-version":[{"id":2826,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/2821\/revisions\/2826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/2822"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=2821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=2821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=2821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}