{"id":4043,"date":"2025-12-29T17:01:29","date_gmt":"2025-12-29T17:01:29","guid":{"rendered":"https:\/\/mznoticia.com.br\/piraidosul\/?p=4043"},"modified":"2025-12-29T17:01:29","modified_gmt":"2025-12-29T17:01:29","slug":"empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul","status":"publish","type":"post","link":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/","title":{"rendered":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul"},"content":{"rendered":"<div>A unidade da Schoeler Agro, localizada em Pira\u00ed do Sul, abriu um novo processo de contrata\u00e7\u00e3o para ampliar seu quadro de funcion\u00e1rios em 2026. A empresa, que segue em ritmo de expans\u00e3o, est\u00e1 recrutando novos colaboradores para diferentes \u00e1reas da granja.<\/div>\n<div><\/div>\n<div>Segundo o an\u00fancio oficial, a Schoeler Agro busca candidatos com ou sem experi\u00eancia, desde que tenham comprometimento, responsabilidade e interesse em atuar no setor agropecu\u00e1rio. A empresa explicou que oferece ambiente estruturado e profissional; oportunidade de crescimento interno; empresa s\u00f3lida e em plena expans\u00e3o e a valoriza\u00e7\u00e3o do trabalho em equipe.<\/div>\n<div><\/div>\n<div><strong>Quem pode se candidatar<\/strong><\/div>\n<div><\/div>\n<div>\u2022Pessoas com ou sem experi\u00eancia pr\u00e9via;<\/div>\n<div>\u2022Profissionais comprometidos;<\/div>\n<div>\u2022Interessados em trabalhar no segmento agro<\/div>\n<div><\/div>\n<div>As entrevistas ser\u00e3o realizadas diretamente na granja nesta ter\u00e7a-feira (30), com atendimento presencial. O n\u00famero exato de vagas n\u00e3o foi divulgada.<\/div>\n<div><\/div>\n<div><strong>Contato para mais informa\u00e7\u00f5es<\/strong><\/div>\n<div><\/div>\n<div>(42) 99928-8901<\/div>\n<div>(42) 99803-0084<\/div>\n<div>recrutamento@schoeler.com.br<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A unidade da Schoeler Agro, localizada em Pira\u00ed do Sul, abriu um novo processo de contrata\u00e7\u00e3o para ampliar seu quadro de funcion\u00e1rios em 2026. A empresa, que segue em ritmo de expans\u00e3o, est\u00e1 recrutando novos colaboradores para diferentes \u00e1reas da granja. Segundo o an\u00fancio oficial, a Schoeler Agro busca candidatos com ou sem experi\u00eancia, desde [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[47],"class_list":["post-4043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-piraidosul","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"A unidade da Schoeler Agro, localizada em Pira\u00ed do Sul, abriu um novo processo de contrata\u00e7\u00e3o para ampliar seu quadro de funcion\u00e1rios em 2026. A empresa, que segue em ritmo de expans\u00e3o, est\u00e1 recrutando novos colaboradores para diferentes \u00e1reas da granja. Segundo o an\u00fancio oficial, a Schoeler Agro busca candidatos com ou sem experi\u00eancia, desde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Mz Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573479951222\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-29T17:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o MZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o MZ\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\"},\"headline\":\"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul\",\"datePublished\":\"2025-12-29T17:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/\"},\"wordCount\":167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/l400a400q80_x2x5256cd11.jpg\",\"keywords\":[\"destaque\"],\"articleSection\":[\"Pira\u00ed do Sul\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/\",\"name\":\"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/l400a400q80_x2x5256cd11.jpg\",\"datePublished\":\"2025-12-29T17:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/l400a400q80_x2x5256cd11.jpg\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/l400a400q80_x2x5256cd11.jpg\",\"width\":400,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#website\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"name\":\"Mz Not\u00edcia\",\"description\":\"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#organization\",\"name\":\"Mz Not\u00edcia\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"contentUrl\":\"https:\\\/\\\/mznoticia.com.br\\\/jaguariaiva\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sem-nome-4-e1741200616392.png\",\"width\":750,\"height\":563,\"caption\":\"Mz Not\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573479951222\",\"https:\\\/\\\/www.instagram.com\\\/mz.jaguariaiva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/#\\\/schema\\\/person\\\/cc272136b0c6ed1997cd28606dbf90fa\",\"name\":\"Reda\u00e7\u00e3o MZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o MZ\"},\"url\":\"https:\\\/\\\/mznoticia.com.br\\\/piraidosul\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/","og_locale":"pt_BR","og_type":"article","og_title":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias","og_description":"A unidade da Schoeler Agro, localizada em Pira\u00ed do Sul, abriu um novo processo de contrata\u00e7\u00e3o para ampliar seu quadro de funcion\u00e1rios em 2026. A empresa, que segue em ritmo de expans\u00e3o, est\u00e1 recrutando novos colaboradores para diferentes \u00e1reas da granja. Segundo o an\u00fancio oficial, a Schoeler Agro busca candidatos com ou sem experi\u00eancia, desde [&hellip;]","og_url":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/","og_site_name":"Mz Not\u00edcias","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573479951222","article_published_time":"2025-12-29T17:01:29+00:00","og_image":[{"width":400,"height":256,"url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o MZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o MZ","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#article","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/"},"author":{"name":"Reda\u00e7\u00e3o MZ","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa"},"headline":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul","datePublished":"2025-12-29T17:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/"},"wordCount":167,"commentCount":0,"publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg","keywords":["destaque"],"articleSection":["Pira\u00ed do Sul"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/","url":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/","name":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul - Mz Not\u00edcias","isPartOf":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg","datePublished":"2025-12-29T17:01:29+00:00","breadcrumb":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#primaryimage","url":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg","contentUrl":"https:\/\/mznoticia.com.br\/piraidosul\/wp-content\/uploads\/2025\/12\/l400a400q80_x2x5256cd11.jpg","width":400,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/mznoticia.com.br\/piraidosul\/empresa-do-agronegocio-divulga-vagas-de-emprego-em-pirai-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mznoticia.com.br\/piraidosul\/"},{"@type":"ListItem","position":2,"name":"Empresa do agroneg\u00f3cio divulga vagas de emprego em Pira\u00ed do Sul"}]},{"@type":"WebSite","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#website","url":"https:\/\/mznoticia.com.br\/piraidosul\/","name":"Mz Not\u00edcia","description":"A informa\u00e7\u00e3o que voc\u00ea precisa na hora certa!","publisher":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mznoticia.com.br\/piraidosul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#organization","name":"Mz Not\u00edcia","url":"https:\/\/mznoticia.com.br\/piraidosul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/","url":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","contentUrl":"https:\/\/mznoticia.com.br\/jaguariaiva\/wp-content\/uploads\/2025\/03\/Design-sem-nome-4-e1741200616392.png","width":750,"height":563,"caption":"Mz Not\u00edcia"},"image":{"@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573479951222","https:\/\/www.instagram.com\/mz.jaguariaiva\/"]},{"@type":"Person","@id":"https:\/\/mznoticia.com.br\/piraidosul\/#\/schema\/person\/cc272136b0c6ed1997cd28606dbf90fa","name":"Reda\u00e7\u00e3o MZ","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0e29877eb71abb1ca9ac61f9a3da0332bb551c0e70c62105a0f1b3c47b3bff5?s=96&d=simple_local_avatar&r=g","caption":"Reda\u00e7\u00e3o MZ"},"url":"https:\/\/mznoticia.com.br\/piraidosul\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/4043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/comments?post=4043"}],"version-history":[{"count":1,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/4043\/revisions"}],"predecessor-version":[{"id":4046,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/posts\/4043\/revisions\/4046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media\/4044"}],"wp:attachment":[{"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/media?parent=4043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/categories?post=4043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mznoticia.com.br\/piraidosul\/wp-json\/wp\/v2\/tags?post=4043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}